{"id":149,"date":"2018-09-29T05:27:05","date_gmt":"2018-09-29T05:27:05","guid":{"rendered":"https:\/\/www.sewbc.com\/?p=149"},"modified":"2018-09-29T05:27:05","modified_gmt":"2018-09-29T05:27:05","slug":"duravel-suspenso-trabalho-plataforma-l-em-forma-de-plataforma-pintura-tectos-altos","status":"publish","type":"post","link":"https:\/\/www.sewbc.com\/pt\/plataforma-de-trabalho-suspensa-duravel-plataforma-em-forma-de-l-pintura-de-tetos-altos-html","title":{"rendered":"plataforma de trabalho suspensa dur\u00e1vel, plataforma em forma de l para pintar tectos altos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-151\" src=\"https:\/\/www.sewbc.com\/wp-content\/uploads\/Factory-price-zlp800-cosmetic-gondola-for-buiding.jpg\" alt=\"Pre\u00e7o de f\u00e1brica-zlp800-cosmetic-gondola-for-buiding\" width=\"640\" height=\"600\" srcset=\"https:\/\/www.sewbc.com\/wp-content\/uploads\/Factory-price-zlp800-cosmetic-gondola-for-buiding.jpg 640w, https:\/\/www.sewbc.com\/wp-content\/uploads\/Factory-price-zlp800-cosmetic-gondola-for-buiding-300x281.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>A\u00e7o pintado \/ galvanizado a quente \/ alum\u00ednio ZLP630 \/ ZLP800 \/ ZLP1000 L em forma de plataforma suspensa para pintura de parede<\/p>\n<p>Dispositivo padr\u00e3o: 2 unidades de talha, 2 pe\u00e7as de trava de seguran\u00e7a, 1 pe\u00e7a de caixa de controle el\u00e9trico, 4 rolos de cabo de a\u00e7o, 1 rolo de corda de seguran\u00e7a, 1 rolo de cabo, contrapeso.<\/p>\n<p>Dispositivo alternativo: Parede contra roletes, rodas do mecanismo de suspens\u00e3o, corte de carga, dispositivo oscilante, enrolador de fio-m\u00e1quina, extens\u00f5es, coberturas de plataformas, etc.<\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td colspan=\"2\"><strong>Modelo de Propriedade No.<\/strong><\/td>\n<td><strong>ZLP630<\/strong><\/td>\n<td><strong>ZLP800<\/strong><\/td>\n<td><strong>ZLP1000<\/strong><\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Carga nominal (kg)<\/td>\n<td>630<\/td>\n<td>800<\/td>\n<td>1000<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Velocidade de eleva\u00e7\u00e3o (m \/ min)<\/td>\n<td>9 \uff5e 11<\/td>\n<td>8 \uff5e 10<\/td>\n<td>8~10<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Pot\u00eancia do motor (kw)<\/td>\n<td>2 \u00d7 1,5 50HZ \/ 60HZ<\/td>\n<td>2 \u00d7 1,8 50HZ \/ 60HZ<\/td>\n<td>2 \u00d7 2,2<\/p>\n<p>50HZ \/ 60HZ<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Torque de freio (Km)<\/td>\n<td>16<\/td>\n<td>16<\/td>\n<td>16<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Faixa de ajuste do \u00e2ngulo da corda de a\u00e7o (\u00b0)<\/td>\n<td>3 \u00b0 - 8 \u00b0<\/td>\n<td>3 \u00b0 - 8 \u00b0<\/td>\n<td>3 \u00b0 - 8 \u00b0<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Dist\u00e2ncia entre dois cabos de a\u00e7o (mm)<\/td>\n<td>\u2264100<\/td>\n<td>\u2264100<\/td>\n<td>\u2264100<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Trecho nominal da viga frontal (mm)<\/td>\n<td>1500<\/td>\n<td>1500<\/td>\n<td>1500<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"5\"><strong>Plataforma suspensa<\/strong><\/td>\n<td>Bloqueio<\/td>\n<td>Liga de alum\u00ednio<\/td>\n<td>Liga de alum\u00ednio<\/td>\n<td>Liga de alum\u00ednio<\/td>\n<\/tr>\n<tr>\n<td>Nr.Of rack de plataforma<\/td>\n<td>\u00danico rack<\/td>\n<td>\u00danico rack<\/td>\n<td>\u00danico rack<\/td>\n<\/tr>\n<tr>\n<td>Plataforma Nr.Of<\/td>\n<td>3<\/td>\n<td>3<\/td>\n<td>3<\/td>\n<\/tr>\n<tr>\n<td>L \u00d7 L \u00d7 A (mm)<\/td>\n<td>(2000 \u00d7 3) \u00d7 690 \u00d7 1300<\/td>\n<td>(2500 \u00d7 3) \u00d7 690 \u00d7 1300<\/td>\n<td>(2500 \u00d7 3) \u00d7 690 \u00d7 1300<\/td>\n<\/tr>\n<tr>\n<td>Peso (kg)<\/td>\n<td>375 Kg<\/td>\n<td>410 kg<\/td>\n<td>455 kg<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Mecanismo de suspens\u00e3o (kg)<\/td>\n<td>2 \u00d7 175 Kg<\/td>\n<td>2 \u00d7 175 Kg<\/td>\n<td>2 \u00d7 175 Kg<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Contrapeso (kg) opcional<\/td>\n<td>25 \u00d7 36pcs<\/td>\n<td>25 \u00d7 40pcs<\/td>\n<td>25 \u00d7 44pcs<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Di\u00e2metro da corda de a\u00e7o (mm)<\/td>\n<td>8.3<\/td>\n<td>8.6 \/ 9.1<\/td>\n<td>8.6 \/ 9.1<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Altura de eleva\u00e7\u00e3o m\u00e1xima (m)<\/td>\n<td>300<\/td>\n<td>300<\/td>\n<td>300<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Velocidade de rota\u00e7\u00e3o do motor (r \/ min)<\/td>\n<td>1420<\/td>\n<td>1420<\/td>\n<td>1420<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Tens\u00e3o (v) 3PHASES<\/td>\n<td>220V \/ 380V \/<\/p>\n<p>415V<\/td>\n<td>220V \/ 380V \/<\/p>\n<p>415V<\/td>\n<td>220V \/ 380V \/<\/p>\n<p>415V<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-156\" src=\"https:\/\/www.sewbc.com\/wp-content\/uploads\/Suspended-Platform.jpg\" alt=\"\" width=\"680\" height=\"453\" srcset=\"https:\/\/www.sewbc.com\/wp-content\/uploads\/Suspended-Platform.jpg 680w, https:\/\/www.sewbc.com\/wp-content\/uploads\/Suspended-Platform-300x200.jpg 300w, https:\/\/www.sewbc.com\/wp-content\/uploads\/Suspended-Platform-370x245.jpg 370w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-157\" src=\"https:\/\/www.sewbc.com\/wp-content\/uploads\/Suspended-Platform2.jpg\" alt=\"\" width=\"680\" height=\"510\" srcset=\"https:\/\/www.sewbc.com\/wp-content\/uploads\/Suspended-Platform2.jpg 680w, https:\/\/www.sewbc.com\/wp-content\/uploads\/Suspended-Platform2-300x225.jpg 300w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Steel Painted \/ Hot Galvanized \/ Aluminum ZLP630 \/ ZLP800 \/ ZLP1000 L Shaped Suspended Platform For Wall Painting Standard Device: 2 pcs of hoist, 2 pcs of safety lock, 1 pc of electric control box, 4 rolls of steel wire rope, 1 roll of safety rope, 1 roll of cable, counter weight. Alternative Device:Wall [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":151,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3],"tags":[],"class_list":["post-149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-products","category-suspended-working-platform-manufacturer"],"_links":{"self":[{"href":"https:\/\/www.sewbc.com\/pt\/wp-json\/wp\/v2\/posts\/149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sewbc.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sewbc.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sewbc.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sewbc.com\/pt\/wp-json\/wp\/v2\/comments?post=149"}],"version-history":[{"count":0,"href":"https:\/\/www.sewbc.com\/pt\/wp-json\/wp\/v2\/posts\/149\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sewbc.com\/pt\/wp-json\/wp\/v2\/media\/151"}],"wp:attachment":[{"href":"https:\/\/www.sewbc.com\/pt\/wp-json\/wp\/v2\/media?parent=149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sewbc.com\/pt\/wp-json\/wp\/v2\/categories?post=149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sewbc.com\/pt\/wp-json\/wp\/v2\/tags?post=149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}