{"id":766,"date":"2018-10-16T09:06:54","date_gmt":"2018-10-16T09:06:54","guid":{"rendered":"https:\/\/www.sewbc.com\/?p=766"},"modified":"2018-10-20T03:54:24","modified_gmt":"2018-10-20T03:54:24","slug":"zlp630-pintado-acero-fachada-limpiador-suspendido-work-platform","status":"publish","type":"post","link":"https:\/\/www.sewbc.com\/gl\/plataforma-de-traballo-suspendida-para-limpeza-de-fachadas-de-aceiro-pintado-zlp630-html","title":{"rendered":"Zlp630 fachada de aceiro pintado limpeza plataforma de traballo suspendida"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-767\" src=\"https:\/\/www.sewbc.com\/wp-content\/uploads\/HuiYang-ZLP800-Electric-Powder-Painting-Working-Platform-1.jpg\" alt=\"\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/www.sewbc.com\/wp-content\/uploads\/HuiYang-ZLP800-Electric-Powder-Painting-Working-Platform-1.jpg 1200w, https:\/\/www.sewbc.com\/wp-content\/uploads\/HuiYang-ZLP800-Electric-Powder-Painting-Working-Platform-1-150x150.jpg 150w, https:\/\/www.sewbc.com\/wp-content\/uploads\/HuiYang-ZLP800-Electric-Powder-Painting-Working-Platform-1-300x300.jpg 300w, https:\/\/www.sewbc.com\/wp-content\/uploads\/HuiYang-ZLP800-Electric-Powder-Painting-Working-Platform-1-768x768.jpg 768w, https:\/\/www.sewbc.com\/wp-content\/uploads\/HuiYang-ZLP800-Electric-Powder-Painting-Working-Platform-1-1024x1024.jpg 1024w, https:\/\/www.sewbc.com\/wp-content\/uploads\/HuiYang-ZLP800-Electric-Powder-Painting-Working-Platform-1-50x50.jpg 50w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p><strong>Informaci\u00f3n b\u00e1sica<\/strong><br \/>\nModelo NO .: zlp630<br \/>\nAncho: 0.69m<br \/>\nMotor: 1.5kw * 2<br \/>\nCor: como \u00e9 necesario<br \/>\nCorda de f\u00edo: 8.3 mm<br \/>\nBloqueo de seguridade: Ldf30<br \/>\nContrapeso: 1t<br \/>\nNome do produto: Plataforma<br \/>\nPaquete de transporte: Contenedor<br \/>\nEspecificaci\u00f3n: lonxitude de 6m<br \/>\nOrixe: China<br \/>\nC\u00f3digo HS: 8428909090<\/p>\n<p><strong>Descrici\u00f3n do produto<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-768\" src=\"https:\/\/www.sewbc.com\/wp-content\/uploads\/Zlp630-Painted-Steel-Facade-Cleaning-Suspended-Working-Platform.jpg\" alt=\"\" width=\"650\" height=\"487\" srcset=\"https:\/\/www.sewbc.com\/wp-content\/uploads\/Zlp630-Painted-Steel-Facade-Cleaning-Suspended-Working-Platform.jpg 650w, https:\/\/www.sewbc.com\/wp-content\/uploads\/Zlp630-Painted-Steel-Facade-Cleaning-Suspended-Working-Platform-300x225.jpg 300w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/p>\n<table border=\"1\">\n<tbody>\n<tr>\n<td>modelo<\/td>\n<td>ZLP630<\/td>\n<td>ZLP800<\/td>\n<\/tr>\n<tr>\n<td>capacidade<\/td>\n<td>630 KG<\/td>\n<td>800 KG<\/td>\n<\/tr>\n<tr>\n<td>Dimensi\u00f3n da plataforma<\/td>\n<td>6 m de lonxitude<\/td>\n<td>Lonxitude de 7.5 m<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>Ancho de 0,69 m<\/td>\n<td>Ancho de 0,69 m<\/td>\n<\/tr>\n<tr>\n<td>Material de plataforma de traballo<br \/>\n(sen inclu\u00edr o feixe de cadro)<\/td>\n<td>Aleaci\u00f3n de aluminio<\/td>\n<td>Aleaci\u00f3n de aluminio<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>Materiais de aceiro con escudo de pintura<\/td>\n<td>Materiais de aceiro con escudo de pintura<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>Materiais de aceiro con capa galvanizada en quente<\/td>\n<td>Materiais de aceiro con capa galvanizada en quente<\/td>\n<\/tr>\n<tr>\n<td>motor<\/td>\n<td>1.5kw * 2 380V, 50HZ<\/td>\n<td>1.8kw * 2 380V, 50HZ<\/td>\n<\/tr>\n<tr>\n<td>cor<\/td>\n<td>Segundo se requira<\/td>\n<td>Segundo se requira<\/td>\n<\/tr>\n<tr>\n<td>Bloqueo de seguridade<\/td>\n<td>LDF30<\/td>\n<td>LST30<\/td>\n<\/tr>\n<tr>\n<td>contrapeso<\/td>\n<td>25 (kg) x40 pezas<br \/>\nTipo de fundici\u00f3n de cemento<br \/>\n(n\u00f3s ofrecemos o molde)<\/td>\n<td>25 (kg) x40 pezas<br \/>\nTipo de fundici\u00f3n de cemento<br \/>\n(n\u00f3s ofrecemos o molde)<\/td>\n<\/tr>\n<tr>\n<td>Especificaci\u00f3n da corda de f\u00edo<\/td>\n<td>De lonxitude de 100 metros<br \/>\nDi\u00e1metro: 8.3 mm<\/td>\n<td>De lonxitude de 100 metros<br \/>\nDi\u00e1metro: 8.6mm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>INFORMACI\u00d3N DE EMBALAXE<\/strong><br \/>\n1. Pel\u00edcula en contenedor por v\u00eda mar\u00edtima ou cami\u00f3n por terra.<br \/>\n2. caixa de aceiro para recambios<\/p>\n<p><strong>INFORMACI\u00d3N DE TRANSPORTE<\/strong><br \/>\n1. Env\u00edalle o video de comisionado antes do env\u00edo;<br \/>\n2. Por mar por bens, para a recepci\u00f3n do porto;<br \/>\n3. Os clientes que especifican os TRANSITARIOS ou os m\u00e9todos de env\u00edo negociables.<br \/>\n4. Prazo de entrega: 5-20 d\u00edas contra o pagamento avanzado.<\/p>\n<p><strong>TERMOS DE PAGO<\/strong><br \/>\n1. Pago: T \/ T, Western Union, MoneyGram, PayPal; Dep\u00f3sitos do 30%; Saldo do 70% antes da entrega.<br \/>\n2. MOQ: conxunto 1.<br \/>\n3. Garant\u00eda: Totalmente de 12 meses para a m\u00e1quina de conxunto completa desde a m\u00e1quina de d\u00eda instalada e funcionando ben.<\/p>\n<p><strong>O noso servizo<\/strong><br \/>\n1.) A entrega oportuna, os enxe\u00f1eiros en espera est\u00e1n preparados para resolver os problemas<br \/>\n2.) Ofrece 12 (doce s\u00f3) meses per\u00edodo de garant\u00eda do produto, con amplas pezas de reposici\u00f3n<br \/>\n3.) Ofrecer orientaci\u00f3n para a instalaci\u00f3n de traballo e adestramento de operaci\u00f3n e mantemento<\/p>","protected":false},"excerpt":{"rendered":"<p>Basic Info Model NO.: zlp630 Width: 0.69m Motor: 1.5kw*2 Color: as Required Wire Rope: 8.3mm Safety Lock: Ldf30 Counterweight: 1t Name of Product: Platform Transport Package: Container Specification: 6m lenght Origin: China HS Code: 8428909090 Product Description model ZLP630 ZLP800 capacity 630 KG 800 KG Platform dimension 6m length 7.5m length 0.69m width 0.69m width [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":767,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[13,16,12,17],"class_list":["post-766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-window-cleaning-platform-manufacturer","tag-rope-suspended-platform-safety","tag-suspended-wire-rope-platform","tag-suspended-working-platform-safety","tag-zlp-630-suspended-platform"],"_links":{"self":[{"href":"https:\/\/www.sewbc.com\/gl\/wp-json\/wp\/v2\/posts\/766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sewbc.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sewbc.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sewbc.com\/gl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sewbc.com\/gl\/wp-json\/wp\/v2\/comments?post=766"}],"version-history":[{"count":0,"href":"https:\/\/www.sewbc.com\/gl\/wp-json\/wp\/v2\/posts\/766\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sewbc.com\/gl\/wp-json\/wp\/v2\/media\/767"}],"wp:attachment":[{"href":"https:\/\/www.sewbc.com\/gl\/wp-json\/wp\/v2\/media?parent=766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sewbc.com\/gl\/wp-json\/wp\/v2\/categories?post=766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sewbc.com\/gl\/wp-json\/wp\/v2\/tags?post=766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}