{"id":172,"date":"2018-09-29T05:37:25","date_gmt":"2018-09-29T05:37:25","guid":{"rendered":"https:\/\/www.sewbc.com\/?p=172"},"modified":"2018-10-19T10:03:39","modified_gmt":"2018-10-19T10:03:39","slug":"plate-forme-suspendue-en-aluminium-en-aluminium-630kg-equipement-suspendu-dacces","status":"publish","type":"post","link":"https:\/\/www.sewbc.com\/fr\/plateforme-suspendue-en-acier-et-aluminium-berceau-630kg-equipement-dacces-suspendu-html","title":{"rendered":"berceau de plate-forme suspendu en acier \/ aluminium, \u00e9quipement d&#039;acc\u00e8s suspendu de 630kg"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-176\" src=\"https:\/\/www.sewbc.com\/wp-content\/uploads\/galvanized-suspended-aerial-work-platform-price-1.jpg\" alt=\"plate-forme-de-travail-aerienne-galvanisee (1)\" width=\"640\" height=\"640\" srcset=\"https:\/\/www.sewbc.com\/wp-content\/uploads\/galvanized-suspended-aerial-work-platform-price-1.jpg 640w, https:\/\/www.sewbc.com\/wp-content\/uploads\/galvanized-suspended-aerial-work-platform-price-1-150x150.jpg 150w, https:\/\/www.sewbc.com\/wp-content\/uploads\/galvanized-suspended-aerial-work-platform-price-1-300x300.jpg 300w, https:\/\/www.sewbc.com\/wp-content\/uploads\/galvanized-suspended-aerial-work-platform-price-1-50x50.jpg 50w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<h3>Charge 630kg chinois fabricant ZLP630 \u00e9chafaudage propuls\u00e9 berceau avec le meilleur prix<\/p>\n<p>Plate-forme suspendue \u00e9lectrique ZLP630<\/h3>\n<hr \/>\n<p>La plate-forme suspendue de la s\u00e9rie ZLP appartient aux machines d&#039;escalade et de d\u00e9coration \u00e0 commande \u00e9lectrique, principalement utilis\u00e9es pour la d\u00e9coration, l&#039;entretien et le nettoyage de la fa\u00e7ade d&#039;immeubles de grande hauteur et de constructions ext\u00e9rieures telles que le rev\u00eatement de ciment, le placage, la peinture, l&#039;installation de murs rideaux en verre comme nettoyage et entretien. Peut \u00e9galement s&#039;appliquer \u00e0 l&#039;exploitation de grands navires et ponts, barrages, etc.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-179\" src=\"https:\/\/www.sewbc.com\/wp-content\/uploads\/Load-630kg-Chinese-manufacturer-ZLP630-scaffolding-powered-cradle-with-best-price.png\" alt=\"\" width=\"680\" height=\"440\" srcset=\"https:\/\/www.sewbc.com\/wp-content\/uploads\/Load-630kg-Chinese-manufacturer-ZLP630-scaffolding-powered-cradle-with-best-price.png 680w, https:\/\/www.sewbc.com\/wp-content\/uploads\/Load-630kg-Chinese-manufacturer-ZLP630-scaffolding-powered-cradle-with-best-price-300x194.png 300w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/p>\n<p>La description:<\/p>\n<hr \/>\n<p>1. Composants principaux: plate-forme, m\u00e9canisme de suspension, palan, verrou de s\u00e9curit\u00e9, syst\u00e8me de contr\u00f4le \u00e9lectrique, c\u00e2ble d&#039;acier, c\u00e2ble, verrou de s\u00e9curit\u00e9.<br \/>\n2. Longueur de la plate-forme : 6M (2M*3SECTIONS) -- peut \u00eatre personnalis\u00e9<br \/>\n3. Puissance de levage: 208V ~ 440V, 50Hz \/ 60Hz<br \/>\n4. M\u00e9canisme de suspension: peint ou galvanis\u00e9 \u00e0 chaud<br \/>\n5. Verrouillage de s\u00e9curit\u00e9: LSD30 (2 pi\u00e8ces par jeu)<br \/>\n6. Syst\u00e8me de contr\u00f4le \u00e9lectrique: pi\u00e8ces internes avec marque CHINT ou SCHNEIDER<br \/>\n7. C\u00e2ble en acier: \u04248,6mm; 100mts \/ pi\u00e8ce (total 4 pi\u00e8ces)<br \/>\n8. C\u00e2ble: 3 * 2.5 + 2 * 1.5, 100 m \/ rouleau<br \/>\n9. Corde de s\u00e9curit\u00e9: 100 m \/ rouleau<br \/>\n10. Contrepoids: ciment, ciment avec rev\u00eatement en acier, fer \u00e0 repasser (3 types en option)<\/p>\n<h3>Fiche technique<\/h3>\n<hr \/>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td colspan=\"2\"><strong>Num\u00e9ro de mod\u00e8le de la propri\u00e9t\u00e9<\/strong><\/td>\n<td><strong>ZLP500<\/strong><\/td>\n<td><strong>ZLP630<\/strong><\/td>\n<td><strong>ZLP800<\/strong><\/td>\n<td><strong>ZLP1000<\/strong><\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Charge nominale (kg)<\/td>\n<td>500<\/td>\n<td>630<\/td>\n<td>800<\/td>\n<td>1000<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Vitesse de levage (m \/ min)<\/td>\n<td>9 \uff5e 11<\/td>\n<td>9 \uff5e 11<\/td>\n<td>8 \uff5e 10<\/td>\n<td>8~10<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Puissance du moteur (kw)<\/td>\n<td>2 \u00d7 1,5 50HZ \/ 60HZ<\/td>\n<td>2 \u00d7 1,5 50HZ \/ 60HZ<\/td>\n<td>2 \u00d7 1,8 50HZ \/ 60HZ<\/td>\n<td>2 \u00d7 2,2<br \/>\n50HZ \/ 60HZ<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Couple de freinage (km)<\/td>\n<td>16<\/td>\n<td>16<\/td>\n<td>16<\/td>\n<td>16<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Plage de r\u00e9glage de l&#039;angle de la corde en acier (\u00b0)<\/td>\n<td>3 \u00b0 - 8 \u00b0<\/td>\n<td>3 \u00b0 - 8 \u00b0<\/td>\n<td>3 \u00b0 - 8 \u00b0<\/td>\n<td>3 \u00b0 - 8 \u00b0<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Distance entre deux c\u00e2bles d&#039;acier (mm)<\/td>\n<td>\u2264100<\/td>\n<td>\u2264100<\/td>\n<td>\u2264100<\/td>\n<td>\u2264100<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Longueur nominale de la poutre avant (mm)<\/td>\n<td>1500<\/td>\n<td>1500<\/td>\n<td>1500<\/td>\n<td>1500<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"5\"><strong>Plate-forme de suspension<\/strong><\/td>\n<td>Verrouillage<\/td>\n<td>Alliage d&#039;aluminium<\/td>\n<td>Alliage d&#039;aluminium<\/td>\n<td>Alliage d&#039;aluminium<\/td>\n<td>Alliage d&#039;aluminium<\/td>\n<\/tr>\n<tr>\n<td>Nr.Of support de plateforme<\/td>\n<td>Rack unique<\/td>\n<td>Rack unique<\/td>\n<td>Rack unique<\/td>\n<td>Rack unique<\/td>\n<\/tr>\n<tr>\n<td>Plateforme Nr.<\/td>\n<td>2<\/td>\n<td>3<\/td>\n<td>3<\/td>\n<td>3<\/td>\n<\/tr>\n<tr>\n<td>L \u00d7 W \u00d7 H (mm)<\/td>\n<td>(2500 \u00d7 2) \u00d7 690 \u00d7 1300<\/td>\n<td>(2000 \u00d7 3) \u00d7 690 \u00d7 1300<\/td>\n<td>(2500 \u00d7 3) \u00d7 690 \u00d7 1300<\/td>\n<td>(2500 \u00d7 3) \u00d7 690 \u00d7 1300<\/td>\n<\/tr>\n<tr>\n<td>Poids (kg)<\/td>\n<td>350 kg<\/td>\n<td>375 kg<\/td>\n<td>410 kg<\/td>\n<td>455 kg<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">M\u00e9canisme de suspension (kg)<\/td>\n<td>2 \u00d7 175 kg<\/td>\n<td>2 \u00d7 175 kg<\/td>\n<td>2 \u00d7 175 kg<\/td>\n<td>2 \u00d7 175 kg<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Contrepoids (kg) en option<\/td>\n<td>25 \u00d7 30pcs<\/td>\n<td>25 \u00d7 36pcs<\/td>\n<td>25 \u00d7 40pcs<\/td>\n<td>25 \u00d7 44pcs<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Diam\u00e8tre de la corde en acier (mm)<\/td>\n<td>8.3<\/td>\n<td>8.3<\/td>\n<td>8.6 \/ 9.1<\/td>\n<td>8.6 \/ 9.1<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Hauteur de levage maximale (m)<\/td>\n<td>300<\/td>\n<td>300<\/td>\n<td>300<\/td>\n<td>300<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Vitesse de rotation du moteur (r \/ min)<\/td>\n<td>1420<\/td>\n<td>1420<\/td>\n<td>1420<\/td>\n<td>1420<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Tension (v)<br \/>\n3 PHASES \/ SIMPLE<\/td>\n<td>220V \/ 380V \/<br \/>\n415V<\/td>\n<td>220V \/ 380V \/<br \/>\n415V<\/td>\n<td>220V \/ 380V \/<br \/>\n415V<\/td>\n<td>220V \/ 380V \/<br \/>\n415V<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Avantages concurrentiels:<\/p>\n<hr \/>\n<p>1. Absolument garantir la s\u00e9curit\u00e9 de la vie pendant le travail a\u00e9rien<br \/>\nUn verrou de s\u00e9curit\u00e9 attache le c\u00e2ble en acier d\u00e8s que la plate-forme suspendue bascule ou que le c\u00e2ble en acier glisse hors du palan; Le syst\u00e8me de commande \u00e9lectrique est con\u00e7u avec une protection contre les fuites, une protection contre la surchauffe, une protection contre les surcharges de courant et un arr\u00eat de frein; c\u00e2ble d&#039;acier, c\u00e2ble et c\u00e2ble de s\u00e9curit\u00e9 de bonne qualit\u00e9.<br \/>\n2. Performance stable: \u00e9lever et abaisser en douceur<br \/>\n3. Conception modulaire. Facile \u00e0 d\u00e9monter, assembler, utiliser et entretenir.<br \/>\n4. La hauteur de levage peut \u00eatre ajust\u00e9e en fonction des besoins (300 m\u00e8tres maximum)<br \/>\n5. La tension et la fr\u00e9quence de travail peuvent \u00eatre ajust\u00e9es (220V \/ 380V \/ 415V, etc.)<br \/>\n6. La plate-forme suspendue \u00e0 usage sp\u00e9cial peut \u00eatre personnalis\u00e9e (circulaire, forme en L, forme en U, etc.)<br \/>\n7. Qualit\u00e9 professionnelle, prix comp\u00e9titif, livraison rapide, bons services.<\/p>","protected":false},"excerpt":{"rendered":"<p>Load 630kg Chinese manufacturer ZLP630 scaffolding powered cradle with best price ZLP630 Electric Suspended Platform ZLP series suspended platform belongs to electrical-driven climbing and decorating machinery, mainly used to decorating,maintaining and cleaning the facade of high-level buildings and exterior construction such as cement coating,veneering,painting,installing the glass curtain walls,painting as well as cleaning and Maintenance. Also [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":176,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3],"tags":[11],"class_list":["post-172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-products","category-suspended-working-platform-manufacturer","tag-suspended-platform-cradle"],"_links":{"self":[{"href":"https:\/\/www.sewbc.com\/fr\/wp-json\/wp\/v2\/posts\/172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sewbc.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sewbc.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sewbc.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sewbc.com\/fr\/wp-json\/wp\/v2\/comments?post=172"}],"version-history":[{"count":0,"href":"https:\/\/www.sewbc.com\/fr\/wp-json\/wp\/v2\/posts\/172\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sewbc.com\/fr\/wp-json\/wp\/v2\/media\/176"}],"wp:attachment":[{"href":"https:\/\/www.sewbc.com\/fr\/wp-json\/wp\/v2\/media?parent=172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sewbc.com\/fr\/wp-json\/wp\/v2\/categories?post=172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sewbc.com\/fr\/wp-json\/wp\/v2\/tags?post=172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}